{"id":427,"date":"2021-09-16T06:00:08","date_gmt":"2021-09-16T09:00:08","guid":{"rendered":"http:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=427"},"modified":"2021-09-14T23:24:30","modified_gmt":"2021-09-15T02:24:30","slug":"invalidez-seria-incapacidade-permanente","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2021\/09\/16\/invalidez-seria-incapacidade-permanente\/","title":{"rendered":"Invalidez seria incapacidade permanente"},"content":{"rendered":"<p style=\"text-align: justify; text-indent: 49.65pt;\"><span style=\"font-size: 14.0pt; font-family: 'Arial',sans-serif; color: #333333;\">Os benef\u00edcios mais importantes do INSS, Seguro Social dos trabalhadores, s\u00e3o os menos desejados, por invalidez ou morte. A aposentadoria por idade e a extinta por tempo de contribui\u00e7\u00e3o s\u00e3o previs\u00edveis e program\u00e1veis, e assim podem ocorrer na previd\u00eancia privada ou mesmo com aplica\u00e7\u00f5es e poupan\u00e7as individuais. E a mais grave perversidade da \u00faltima reforma previdenci\u00e1ria \u2013 c\u00e1lculo em 60% da m\u00e9dia para quem tiver at\u00e9 20 anos de contribui\u00e7\u00e3o, com o acr\u00e9scimo de 2% para cada ano a partir da\u00ed \u2013 tamb\u00e9m se aplica nos benef\u00edcios decorrentes de sinistros.<\/span><\/p>\n<p style=\"text-align: justify; text-indent: 49.65pt;\"><span style=\"font-size: 14.0pt; font-family: 'Arial',sans-serif; color: #333333;\">O retrocesso legal \u00e9 bastante evidente. Na lei de 1991, regulamentando a Constitui\u00e7\u00e3o Cidad\u00e3, a aposentadoria por invalidez pagaria 80% da m\u00e9dia contributiva, com mais 1% para cada ano de contribui\u00e7\u00e3o. Portanto, com 20 anos de contribui\u00e7\u00e3o ou mais, atingiria 100%. Ressalte-se que a invalidez por acidente do trabalho dispunha 100% sempre. Em 1995, com m\u00e1s inten\u00e7\u00f5es, veio a iguala\u00e7\u00e3o aos benef\u00edcios acident\u00e1rios, com a invalidez pagando 100% da m\u00e9dia em qualquer caso. A Emenda Constitucional n\u00ba 103\/2019 determina o pagamento em 60% para quem tiver at\u00e9 20 anos de contribui\u00e7\u00e3o, acrescentando 2% para cada ano a partir da\u00ed. Enquanto o m\u00ednimo na lei de 1991 era 80%, 20 anos de contribui\u00e7\u00e3o faziam alcan\u00e7ar 100%; agora, at\u00e9 20 anos de contribui\u00e7\u00e3o garantem apenas 60%?!<\/span><\/p>\n<p style=\"text-align: justify; text-indent: 49.65pt;\"><span style=\"font-size: 14.0pt; font-family: 'Arial',sans-serif; color: #333333;\">A invalidez por acidente do trabalho volta a pagar 100%, qualquer quer seja o tempo de contribui\u00e7\u00e3o, mas o novo c\u00e1lculo do benef\u00edcio previdenci\u00e1rio, a partir de 60%, alcan\u00e7ando 100% apenas com 40 anos de contribui\u00e7\u00e3o, \u00e9 insustent\u00e1vel. Pior ainda com o aux\u00edlio-doen\u00e7a, por incapacidade tempor\u00e1ria, pagando 91% da m\u00e9dia, com qualquer tempo de contribui\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify; text-indent: 49.65pt;\"><span style=\"font-size: 14.0pt; font-family: 'Arial',sans-serif; color: #333333;\">Fazendo as contas, veremos que apenas com 36 anos de contribui\u00e7\u00e3o o segurado teria sua aposentadoria por invalidez maior do que o aux\u00edlio-doen\u00e7a. Dif\u00edcil explicar que o benef\u00edcio por incapacidade permanente pague menos do que o por incapacidade tempor\u00e1ria. Demonstra apenas o excesso de maldade, com a aposentadoria para sempre pagando um valor menor.<\/span><\/p>\n<p style=\"text-align: justify; text-indent: 49.65pt;\"><span style=\"font-size: 14.0pt; font-family: 'Arial',sans-serif; color: #333333;\">Pior de tudo foram os arrast\u00f5es periciais, cassando um monte de aposentadorias por invalidez de trabalhadores que continuam absolutamente incapacitados. Em muitas a\u00e7\u00f5es judiciais, o INSS tem sido condenado a \u2013 ao inv\u00e9s de recolocar em manuten\u00e7\u00e3o a aposentadoria por invalidez \u2013 conceder aux\u00edlio-doen\u00e7a e reabilita\u00e7\u00e3o profissional. Como reabilita\u00e7\u00e3o de verdade n\u00e3o existe, \u00e9 bem poss\u00edvel que o INSS resolva converter o aux\u00edlio-doen\u00e7a em aposentadoria por invalidez, com os novos c\u00e1lculos.<\/span><\/p>\n<p style=\"text-align: justify; text-indent: 49.65pt;\"><span style=\"font-size: 14.0pt; font-family: 'Arial',sans-serif; color: #333333;\">Imaginem: Jo\u00e3o, com 20 anos de contribui\u00e7\u00e3o como industri\u00e1rio de n\u00edvel t\u00e9cnico, foi aposentado por invalidez, recebendo 100% de sua m\u00e9dia contributiva, R$ 4.000. Ap\u00f3s 15 anos como aposentado, 57 de idade, teve seu benef\u00edcio cassado em uma per\u00edcia vergonhosa e superficial. Com vit\u00f3ria parcial na a\u00e7\u00e3o que ajuizou, Jo\u00e3o passa a receber aux\u00edlio-doen\u00e7a, no valor de R$ 3.640. Ap\u00f3s dois anos aguardando uma reabilita\u00e7\u00e3o profissional que n\u00e3o ocorre, Jo\u00e3o \u00e9 novamente aposentado por invalidez, dessa vez com a renda mensal de R$ 2.400.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os novos c\u00e1lculos na concess\u00e3o das aposentadorias por invalidez e das pens\u00f5es por morte representam a mais grave perversidade na EC 103\/2019, afrontando diretamente o internacional Princ\u00edpio do N\u00e3o Retrocesso no Direito Social.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-427","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/427\/revisions"}],"predecessor-version":[{"id":428,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/427\/revisions\/428"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}