{"id":561,"date":"2022-03-14T06:00:26","date_gmt":"2022-03-14T09:00:26","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=561"},"modified":"2022-03-11T18:22:12","modified_gmt":"2022-03-11T21:22:12","slug":"o-passa-moleque-do-stf","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2022\/03\/14\/o-passa-moleque-do-stf\/","title":{"rendered":"O passa-moleque do STF"},"content":{"rendered":"<p>\u00c9 dif\u00edcil de acreditar, mas o Tribunal M\u00e1ximo de nosso Pa\u00eds aplicou uma pe\u00e7a de muito mau gosto aos aposentados. Depois de muita comemora\u00e7\u00e3o pelos 6 a 5 em favor da revis\u00e3o das aposentadorias pela m\u00e9dia da vida toda, um ministro, dessas cria\u00e7\u00f5es do atual desgoverno, apresenta um destaque para invalidar todos os votos e come\u00e7ar tudo de novo no plen\u00e1rio presencial.<br \/>\nS\u00f3 pra lembrar, a decis\u00e3o do STF foi que regra de transi\u00e7\u00e3o n\u00e3o pode ter aplica\u00e7\u00e3o obrigat\u00f3ria, serve apenas quando mais favor\u00e1vel. Assim, a Lei 9.876\/1999 substituiu, enquanto base de c\u00e1lculo para benef\u00edcios previdenci\u00e1rios, a m\u00e9dia dos 36 \u00faltimos sal\u00e1rios pela \u201cdos maiores sal\u00e1rios-de-contribui\u00e7\u00e3o correspondente a oitenta por cento de todo o per\u00edodo contributivo\u201d, com a regra de transi\u00e7\u00e3o, para quem j\u00e1 estava no sistema previdenci\u00e1rio, dispondo o \u201cper\u00edodo contributivo desde a compet\u00eancia julho de 1994\u201d. E tal forma de c\u00e1lculo vale at\u00e9 13\/11\/2019, promulga\u00e7\u00e3o da EC 103.<br \/>\nAcontece que a regra de transi\u00e7\u00e3o em uma emenda constitucional existe para que os trabalhadores que j\u00e1 estavam no sistema previdenci\u00e1rio n\u00e3o sofram todas as agruras da nova regra. Ou seja, s\u00f3 pode ser aplicada quando mais favor\u00e1vel<br \/>\nObservando a decad\u00eancia, prazo de dez anos da data da concess\u00e3o do benef\u00edcio para reclamar, quem se aposentou antes de mar\u00e7o de 2012 perdeu o prazo. Restam para brigar, al\u00e9m dos que j\u00e1 ajuizaram a a\u00e7\u00e3o, os aposentados que, comprovando a m\u00e9dia das contribui\u00e7\u00f5es da vida toda superior \u00e0 utilizada pelo INSS, a partir da compet\u00eancia julho de 1994, devem ter a concess\u00e3o de seu benef\u00edcio entre abril de 2012 e novembro de 2019.<br \/>\nSendo mat\u00e9ria de Direito Social, j\u00e1 \u00e9 uma baita vergonha a conclus\u00e3o da vota\u00e7\u00e3o com apenas um voto de diferen\u00e7a a favor dos aposentados, mas esse passa-moleque com um destaque de ministro que nem havia participado, cancelando o julgamento virtual e voltando tudo para o zero a zero, \u00e9 demais.<br \/>\nE assim \u00e9 poss\u00edvel que o voto favor\u00e1vel do relator Marco Aur\u00e9lio Mello simplesmente desapare\u00e7a e consigam inverter a decis\u00e3o. Seria uma degenera\u00e7\u00e3o jur\u00eddica, um achincalhe para o Superior Tribunal. Vale lutar em todas as frentes para que confirmem a decis\u00e3o virtual comemorada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parece inacredit\u00e1vel, depois de muita comemora\u00e7\u00e3o sobre uma decis\u00e3o acertada, o STF se desfaz da vota\u00e7\u00e3o conclu\u00edda no julgamento virtual, levando ao plen\u00e1rio presencial.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-561","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=561"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/561\/revisions"}],"predecessor-version":[{"id":562,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/561\/revisions\/562"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}