{"id":567,"date":"2022-03-21T06:00:42","date_gmt":"2022-03-21T09:00:42","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=567"},"modified":"2022-03-17T18:08:54","modified_gmt":"2022-03-17T21:08:54","slug":"vamos-entender-a-media-da-vida-toda-2","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2022\/03\/21\/vamos-entender-a-media-da-vida-toda-2\/","title":{"rendered":"Entendendo a m\u00e9dia da vida toda"},"content":{"rendered":"<p>S\u00f3 mesmo o Tribunal M\u00e1ximo de nosso Pa\u00eds para pregar uma pe\u00e7a dessas em tantos aposentados. Primeiro conclu\u00edram o julgamento virtual e, com um s\u00f3 voto de diferen\u00e7a, decidiram que regra de transi\u00e7\u00e3o s\u00f3 se aplica quando mais favor\u00e1vel, e assim, muitas aposentadorias deveriam ser recalculadas quando a m\u00e9dia das contribui\u00e7\u00f5es da vida toda for maior do que a de julho de 1994 em diante. Agora, passado menos de um m\u00eas, puxam um coringa da manga, transformando o julgamento virtual em presencial, desprezando todos os votos j\u00e1 lan\u00e7ados, talvez inclusive do relator Marco Aur\u00e9lio Mello, que j\u00e1 n\u00e3o \u00e9 mais ministro. E assim reiniciando a vota\u00e7\u00e3o, com grandes chances de inverter o resultado.<br \/>\nVale recordar qual \u00e9 a briga: a Lei 9.876\/1999 alterou a base de c\u00e1lculo das aposentadorias; em vez da m\u00e9dia dos 36 \u00faltimos sal\u00e1rios, passou a ser a \u201cdos maiores sal\u00e1rios-de-contribui\u00e7\u00e3o correspondente a oitenta por cento de todo o per\u00edodo contributivo\u201d. Por influ\u00eancia da tecnocracia, sem qualquer sentido jur\u00eddico, a lei disp\u00f4s uma regra de transi\u00e7\u00e3o para quem j\u00e1 estava no sistema previdenci\u00e1rio: a m\u00e9dia seria do \u201cper\u00edodo contributivo desde a compet\u00eancia julho de 1994\u201d, simplesmente porque era o in\u00edcio do real e ficaria mais f\u00e1cil efetuar as atualiza\u00e7\u00f5es. Acontece que a regra de transi\u00e7\u00e3o em uma emenda constitucional existe para que os trabalhadores que j\u00e1 estavam no sistema previdenci\u00e1rio n\u00e3o sofram todas as agruras da nova regra. Ou seja, s\u00f3 pode ser aplicada quando mais favor\u00e1vel.<br \/>\nEm muitos casos, os trabalhadores tinham contribui\u00e7\u00f5es maiores antes de julho de 1994, e, assim, teriam a m\u00e9dia da vida toda maior. Por\u00e9m, para o ajuizamento da a\u00e7\u00e3o \u00e9 preciso provar tal alega\u00e7\u00e3o. E, em novembro de 2019, a EC 103 determinou que a m\u00e9dia seria de todas as contribui\u00e7\u00f5es a partir da compet\u00eancia julho de 1994. Sem retirar os menores que representassem 20% e sem regra de transi\u00e7\u00e3o; e, em 1999, este advogado achava que pior n\u00e3o ficaria&#8230;<br \/>\nAl\u00e9m da a\u00e7\u00e3o da m\u00e9dia da vida toda s\u00f3 se aplicar ao aposentado que tiver maiores contribui\u00e7\u00f5es antes de julho de 1994, ainda tem a perversidade chamada decad\u00eancia. Passados dez anos da concess\u00e3o do benef\u00edcio, n\u00e3o pode mais reclamar qualquer erro que possa ter acontecido. Portanto, quem se aposentou antes de mar\u00e7o de 2012 perdeu a chance. Observando princ\u00edpios do Direito Social, a decad\u00eancia \u00e9 maior estult\u00edcia que poderia aparecer; se o aposentado continua recebendo todo m\u00eas um valor mensal menor do que teria direito, pode at\u00e9 perder os saldos que fazem mais de cinco anos, essa \u00e9 a prescri\u00e7\u00e3o, mas ter que se conformar mensalmente com o erro, \u00e9 demais!<br \/>\nDe qualquer forma, o aposentado que pretende ajuizar tal a\u00e7\u00e3o, al\u00e9m de provar que sua m\u00e9dia das contribui\u00e7\u00f5es da vida toda \u00e9 maior do que a que foi utilizada pelo INSS (de julho de 1994 em diante), deve ter o in\u00edcio da sua aposentadoria entre abril de 2012 e novembro de 2019 (EC 103).<br \/>\nOs tecnocratas que servem ao atual desgoverno apresentaram aos jornais um n\u00famero fantasioso do que seria a despesa com essas a\u00e7\u00f5es. \u00c9 evidente que fizeram uma proje\u00e7\u00e3o absurda, buscando assustar os julgadores, e o STF, com um passa-moleque vergonhoso \u2013 alterar o julgamento virtual j\u00e1 conclu\u00eddo, para um presencial, com todo mundo votando de novo \u2013, desfaz, na pr\u00e1tica, a decis\u00e3o que tanto tinha sido comemorada em todo o pa\u00eds.<br \/>\nEsperamos que, com um pouco de dec\u00eancia, o STF confirme a vit\u00f3ria dos aposentados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado na Tribuna Livre em 17\/03\/2022.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-567","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=567"}],"version-history":[{"count":2,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/567\/revisions"}],"predecessor-version":[{"id":569,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/567\/revisions\/569"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}