{"id":642,"date":"2022-06-30T06:00:08","date_gmt":"2022-06-30T09:00:08","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=642"},"modified":"2022-06-29T17:40:20","modified_gmt":"2022-06-29T20:40:20","slug":"reconquistar-a-aposentadoria-especial","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2022\/06\/30\/reconquistar-a-aposentadoria-especial\/","title":{"rendered":"Reconquistar a Aposentadoria Especial"},"content":{"rendered":"<p>A Aposentadoria Especial, com 25, 20 ou mesmo 15 anos de atividades em condi\u00e7\u00f5es insalubres, periculosas ou penosas, conquistada em 1960. Era uma esp\u00e9cie de Aposentadoria por Tempo de Servi\u00e7o (35\/30), com a exig\u00eancia temporal reduzida.<br \/>\nSe a EC 103\/2019 extinguiu a Aposentadoria por Tempo de Contribui\u00e7\u00e3o, arrastou junto a Especial; com a morte jur\u00eddica do principal&#8230;<br \/>\nRestaria, como benef\u00edcio programado, apenas a Aposentadoria por Idade, aos 65 anos para o homem e 62 para a mulher. Assim, a Especial passa a ser uma esp\u00e9cie dessa, com alguma redu\u00e7\u00e3o na exig\u00eancia et\u00e1ria. Quem tiver o tempo m\u00ednimo em atividade especial, 25 anos (mais geral), 20 anos (mineiro de superf\u00edcie) e 15 anos (mineiro de subsolo), ter\u00e1 a diminui\u00e7\u00e3o para, respectivamente, 60, 58 ou 55 anos de idade.<br \/>\nDepois de muitas perversidades, desde 1995, nas altera\u00e7\u00f5es legislativas e especialmente nas interpreta\u00e7\u00f5es pelo INSS, em 13\/11\/2019, ocorreu a promulga\u00e7\u00e3o da EC 103. Quem, at\u00e9 aquela data, havia completado as exig\u00eancias para o benef\u00edcio, tem direito adquirido, mesmo que s\u00f3 consiga fazer valer atrav\u00e9s do Poder Judici\u00e1rio. Os que ingressaram no sistema depois dessa data, n\u00e3o poder\u00e3o reclamar, v\u00e3o se submeter \u00e0 regra nova, apenas com a redu\u00e7\u00e3o da idade para os que tenham trabalhado em condi\u00e7\u00f5es especiais no m\u00ednimo pelo tempo que lhes daria o direito a se aposentar pela regra anterior. E, quem j\u00e1 estava no sistema, mas ainda n\u00e3o havia completado as exig\u00eancias, obedecer\u00e1 \u00e0s perversas regras de transi\u00e7\u00e3o.<br \/>\nPortanto, a regra v\u00e1lida para quem come\u00e7a agora, disp\u00f5e a redu\u00e7\u00e3o na idade com a comprova\u00e7\u00e3o da exposi\u00e7\u00e3o do trabalhador ao per\u00edodo integral em condi\u00e7\u00f5es especiais (25\/60, 20\/58 ou 15\/55 anos), por\u00e9m, vale lembrar, o c\u00e1lculo disposto na emenda constitucional exige 40 anos de contribui\u00e7\u00e3o para atingir 100% da m\u00e9dia.<br \/>\nPara quem j\u00e1 estava no sistema, mas sem completar o per\u00edodo especial, ao inv\u00e9s da idade m\u00ednima, a transi\u00e7\u00e3o exige \u2013 al\u00e9m do tempo completo em atividades insalubres, periculosas ou penosas \u2013 a somat\u00f3ria da idade com todo o tempo de contribui\u00e7\u00e3o, valendo somar tempo comum. Com o m\u00ednimo de 25 anos de exposi\u00e7\u00e3o aos agentes nocivos, como calor e ru\u00eddo, a somat\u00f3ria obrigat\u00f3ria \u00e9 86, para 20 anos \u00e9 76, e para 15 anos, em minas de subsolo, a soma idade e tempo de contribui\u00e7\u00e3o dever\u00e1 ser 66.<br \/>\nUm bom exemplo da confus\u00e3o: pela regra para quem come\u00e7a ap\u00f3s a EC 103, al\u00e9m de 25 anos expostos aos agentes nocivos, ainda precisa da idade m\u00ednima de 60 anos; pela transi\u00e7\u00e3o, para atingir a somat\u00f3ria 86, se o pe\u00e3o tem apenas os 25 anos completos em atividade especial, a idade m\u00ednima sobe para 61 anos. Ainda bem que para a somat\u00f3ria tamb\u00e9m vale o tempo comum.<br \/>\nCom exce\u00e7\u00e3o apenas para quem tinha direito adquirido, o valor do benef\u00edcio ser\u00e1 calculado em 60% da m\u00e9dia de todas as contribui\u00e7\u00f5es desde julho\/1994 para os primeiros 20 anos de contribui\u00e7\u00e3o, acrescentando 2% para cada ano a mais. Portanto, com 25 anos de trabalho em condi\u00e7\u00f5es especiais, ter\u00e1 70% da m\u00e9dia.<br \/>\nOs trabalhadores que completaram seu tempo especial antes de 13\/11\/2019 ter\u00e3o direito adquirido, mas, na maioria das vezes, s\u00f3 conseguir\u00e3o o benef\u00edcio judicialmente. Na regra de transi\u00e7\u00e3o, para quem j\u00e1 estava no sistema previdenci\u00e1rio, sem totalizar o tempo, teremos a exig\u00eancia da somat\u00f3ria da idade com tempo de contribui\u00e7\u00e3o, al\u00e9m do tempo especial completo. Os que ingressaram depois, se aposentar\u00e3o voluntariamente apenas por idade, com a redu\u00e7\u00e3o (60, 58 ou 55), se comprovarem os tempos m\u00ednimos (25, 20 ou 15 anos) submetidos aos agentes qu\u00edmicos, f\u00edsicos ou biol\u00f3gicos prejudiciais \u00e0 sa\u00fade.<br \/>\nCom a recupera\u00e7\u00e3o do Estado Democr\u00e1tico de Direito, a contrarreforma previdenci\u00e1ria dever\u00e1 dar a devida aten\u00e7\u00e3o ao tema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Aposentadoria Especial foi uma importante conquista dos trabalhadores em 1960, e, ap\u00f3s os graves desmontes pelo neoliberalismo, foi praticamente destru\u00edda pela EC 103\/2019, acompanhando a extin\u00e7\u00e3o da Aposentadoria por Tempo de Contribui\u00e7\u00e3o.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-642","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=642"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/642\/revisions"}],"predecessor-version":[{"id":643,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/642\/revisions\/643"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}