{"id":678,"date":"2022-08-29T06:00:45","date_gmt":"2022-08-29T09:00:45","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=678"},"modified":"2022-08-27T20:40:56","modified_gmt":"2022-08-27T23:40:56","slug":"a-historia-do-direito-social","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2022\/08\/29\/a-historia-do-direito-social\/","title":{"rendered":"A Hist\u00f3ria do Direito Social"},"content":{"rendered":"<p>Conforme o colunista disse, a interpreta\u00e7\u00e3o da lei exige uma an\u00e1lise hist\u00f3rica; n\u00e3o basta ler o que est\u00e1 escrito, \u00e9 preciso entender a hist\u00f3ria da sua cria\u00e7\u00e3o. Sem qualquer d\u00favida, antes do Direito sempre existiram as contradi\u00e7\u00f5es, e o Direito Social foi objeto de luta at\u00e9 para a sua equipara\u00e7\u00e3o com o Direito Pol\u00edtico e o Direito Econ\u00f4mico.<br \/>\nOs trinta anos de neoliberalismo, culminando com a covid19, muito fustigaram o Direito Social, reduzindo as garantias trabalhistas e previdenci\u00e1rias. Ser\u00e1 preciso recompor os contratos formais de trabalho e todas as suas consequ\u00eancias.<br \/>\nO Estado Democr\u00e1tico de Direito precisa, al\u00e9m de ser recuperado onde houveram rupturas \u2013 golpe de 2016 etc. \u2013, da busca de sua plenitude, buscando a redu\u00e7\u00e3o da vergonhosa desigualdade social que o pa\u00eds apresenta.<br \/>\nO Mundo Velho, por um lado se rende ao armamentismo, tomando como desculpa o conflito R\u00fassia e Ucr\u00e2nia, por outro compreendeu os absurdos neoliberais, apontando para as contrarreformas nas normas trabalhistas e previdenci\u00e1rias. A pandemia bem demonstrou as exig\u00eancias da civiliza\u00e7\u00e3o. Redu\u00e7\u00e3o das desigualdades sociais e garantias aos hipossuficientes, aos que mais precisam, dever\u00e1 ser o objetivo das for\u00e7as democr\u00e1ticas. A Solidariedade ter\u00e1 que se inscrita nas legisla\u00e7\u00f5es nacionais e nos acordos e tratados internacionais. Sob pena da humanidade enfrentar intermin\u00e1veis pandemias, ser\u00e1 preciso dividir conhecimento e ci\u00eancia, vacinas e rem\u00e9dios.<br \/>\nNa nossa legisla\u00e7\u00e3o trabalhista e previdenci\u00e1ria, al\u00e9m da revoga\u00e7\u00e3o das reformas, respectivamente de 2017 e de 2019, ainda precisaremos de normas para a modernidade, mas sem esquecer a fun\u00e7\u00e3o protetiva para os trabalhadores nas rela\u00e7\u00f5es com o Capital.<br \/>\nRecuperar nossas ind\u00fastrias n\u00e3o ser\u00e1 tarefa f\u00e1cil, exigir\u00e1 recompor a credibilidade internacional do pa\u00eds e muito mais. Por\u00e9m, as garantias dos contratos de trabalho formais, inclusive para o sistema previdenci\u00e1rio, s\u00e3o bandeiras de luta imediatas.<br \/>\nO Estado do Bem-Estar Social foi implantado na Europa no final de Segunda Guerra, respondendo ao bloco socialista que se fortalecia. O desmonte nas regras trabalhistas causado pela pol\u00edtica neoliberal e globalizante representou um retrocesso nas regras entre Capital e Trabalho, aumentando a mis\u00e9ria e instigando a forma\u00e7\u00e3o pol\u00edtica fascista, apostando na ignor\u00e2ncia, no medo e na viol\u00eancia.<br \/>\nO Direito Social \u00e9 o direito de conquistas; \u00e9 fruto objetivo da luta de classes. E o Estado Democr\u00e1tico de Direito que queremos para o nosso pa\u00eds deve buscar seu sentido pleno, reduzindo a mis\u00e9ria e a fome.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Direito Social faz parte da Civiliza\u00e7\u00e3o, em defesa dos hipossuficientes.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-678","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=678"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/678\/revisions"}],"predecessor-version":[{"id":679,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/678\/revisions\/679"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}