{"id":680,"date":"2022-09-01T06:00:15","date_gmt":"2022-09-01T09:00:15","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=680"},"modified":"2022-08-31T18:44:30","modified_gmt":"2022-08-31T21:44:30","slug":"lutar-pelo-salario-minimo","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2022\/09\/01\/lutar-pelo-salario-minimo\/","title":{"rendered":"Lutar pelo Sal\u00e1rio M\u00ednimo"},"content":{"rendered":"<p>O colunista disse muitas vezes que nos tempos de crise, como a pandemia, o que movimenta a economia s\u00e3o os mercados de base; s\u00f3 gasta quem precisa gastar: os pobres. Portanto, buscar um sal\u00e1rio m\u00ednimo com razo\u00e1vel poder de compra \u00e9 uma necessidade imediata para recompor a nossa economia. Apenas os mais incapazes deixam de compreender.<br \/>\nE tem tecnocrata perverso alegando que para destinar aumentos reais ao sal\u00e1rio m\u00ednimo seria preciso desvincular do valor m\u00ednimo para os benef\u00edcios previdenci\u00e1rios. Querem poupar matando os aposentados de fome!<br \/>\n\u00c9 importante lembrar que na Constitui\u00e7\u00e3o Cidad\u00e3 de 1988 consta que os benef\u00edcios substitutivos da remunera\u00e7\u00e3o mensal do trabalhador, como aposentadoria ou pens\u00e3o por morte, n\u00e3o podem ser menores do que o sal\u00e1rio m\u00ednimo. Parece muito claro, se est\u00e3o substituindo o sal\u00e1rio, deve ser, no m\u00ednimo, o m\u00ednimo. Nos tempos da ditadura militar o piso m\u00ednimo das aposentadorias era 95% do sal\u00e1rio m\u00ednimo.<br \/>\nPara as contribui\u00e7\u00f5es deve se obedecer ao sal\u00e1rio m\u00ednimo, com valor menor n\u00e3o vale. Quando o contratado para trabalho intermitente n\u00e3o consegue completar um sal\u00e1rio m\u00ednimo, o m\u00eas n\u00e3o conta para a aposentadoria. Uma portaria cheia de \u201cbondades\u201d determinou que sejam somados os meses seguintes at\u00e9 alcan\u00e7ar o sal\u00e1rio m\u00ednimo, quando ent\u00e3o valer\u00e1 um m\u00eas.<br \/>\nA contrarreforma no Direito Social ter\u00e1 que extirpar esse tipo de contrato, mais barato para o patr\u00e3o que a escravid\u00e3o. A garantia constitucional do piso m\u00ednimo para benef\u00edcios previdenci\u00e1rios nos parece cl\u00e1usula p\u00e9trea, que n\u00e3o pode ser removida. Por\u00e9m, sempre \u00e9 preciso cerrar fileiras em defesa das conquistas.<br \/>\nA esperan\u00e7a \u00e9 um novo governo, com a constru\u00e7\u00e3o de um Estado Democr\u00e1tico de Direito buscando sua aplica\u00e7\u00e3o plena. O neoliberalismo foi esgotado, a sociedade exige a reconstru\u00e7\u00e3o de garantias sociais em todo o mundo. A luta contra a desigualdade social dever\u00e1 alcan\u00e7ar a solidariedade efetiva, disposta na legisla\u00e7\u00e3o e nos acordos e tratados internacionais.<br \/>\nUma as condi\u00e7\u00f5es mais importantes para a redu\u00e7\u00e3o das desigualdades \u00e9 a consolida\u00e7\u00e3o do sal\u00e1rio m\u00ednimo, com aumentos reais efetivos, melhorando substancialmente o poder aquisitivo das classes mais pobres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aumento real para o sal\u00e1rio m\u00ednimo \u00e9 uma obriga\u00e7\u00e3o antiga para os que defendem a Civiliza\u00e7\u00e3o.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-680","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=680"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/680\/revisions"}],"predecessor-version":[{"id":681,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/680\/revisions\/681"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}