{"id":690,"date":"2022-09-15T06:00:40","date_gmt":"2022-09-15T09:00:40","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=690"},"modified":"2022-09-14T19:17:46","modified_gmt":"2022-09-14T22:17:46","slug":"entenda-a-reciprocidade","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2022\/09\/15\/entenda-a-reciprocidade\/","title":{"rendered":"Entenda a reciprocidade"},"content":{"rendered":"<p>A contagem rec\u00edproca de tempo de contribui\u00e7\u00e3o de um regime previdenci\u00e1rio para outro \u00e9 um princ\u00edpio garantido na Constitui\u00e7\u00e3o. A partir de 1998, com a disposi\u00e7\u00e3o de contribui\u00e7\u00f5es para os servidores p\u00fablicos, a reciprocidade passou a exigir tamb\u00e9m a transfer\u00eancia das contribui\u00e7\u00f5es. Para o trabalhador, o principal \u00e9 poder contar o tempo de um regime para o outro.<br \/>\nDe um regime para outro \u00e9 necess\u00e1rio requerer uma certid\u00e3o do tempo de contribui\u00e7\u00e3o para realizar a averba\u00e7\u00e3o. E \u00e9 importante observar que tempos concomitantes n\u00e3o contam duas vezes. Ou seja, quando trabalhou ao mesmo tempo vinculado ao INSS e, como servidor p\u00fablico, ao Regime Pr\u00f3prio dos servidores p\u00fablicos, n\u00e3o poder\u00e1 contar duas vezes o mesmo tempo.<br \/>\nAs regras dos Regimes Pr\u00f3prios dos servidores cada vez mais est\u00e3o se aproximando das do Regime Geral (INSS). Muita gente diz que mais hora menos hora esse ir\u00e1 engolir aqueles. At\u00e9 l\u00e1 ainda existem normas diferenciadas, inclusive no c\u00e1lculo das aposentadorias. At\u00e9 1998, a aposentadoria dos servidores p\u00fablicos era calculada pelo \u00faltimo sal\u00e1rio, acompanhava os reajustes dos servidores em atividade e o teto era o mesmo para sal\u00e1rios e aposentadorias, enquanto o INSS sempre calculou atrav\u00e9s de uma m\u00e9dia contributiva, com o reajuste pela infla\u00e7\u00e3o oficial e com limite bem menor do que o salarial dos servidores p\u00fablicos.<br \/>\nMuitas vezes a contagem rec\u00edproca \u00e9 mais interessante do INSS para o servi\u00e7o p\u00fablico, por\u00e9m, cada vez mais as regras ficam mais parecidas, valendo contar o contr\u00e1rio. Sempre lembrando que os servidores mais antigos ainda t\u00eam vantagens bem maiores nos Regimes Pr\u00f3prios.<br \/>\nO Princ\u00edpio da Reciprocidade foi uma conquista dura para os trabalhadores e muito importante. Ressaltando que, cada vez mais, o Regime Geral de Previd\u00eancia Social poder\u00e1 englobar todos os Regimes Pr\u00f3prios dos servidores p\u00fablicos. O tempo dir\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Princ\u00edpio da Reciprocidade garante a contagem de tempo de um regime previdenci\u00e1rio para outro, como por exemplo do INSS para o Regime Pr\u00f3prio dos servidores p\u00fablicos.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-690","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=690"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/690\/revisions"}],"predecessor-version":[{"id":691,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/690\/revisions\/691"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}