{"id":701,"date":"2022-10-03T06:00:34","date_gmt":"2022-10-03T09:00:34","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=701"},"modified":"2022-09-30T13:32:01","modified_gmt":"2022-09-30T16:32:01","slug":"a-esperanca-voltou","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2022\/10\/03\/a-esperanca-voltou\/","title":{"rendered":"A esperan\u00e7a voltou!"},"content":{"rendered":"<p>O colunista batuca essas linhas na sexta-feira, com a certeza de que hoje, segunda-feira, 03\/10\/2022, estaremos todos comemorando a volta da esperan\u00e7a.<br \/>\nRetorna a esperan\u00e7a de reconstruir o Brasil, suas institui\u00e7\u00f5es e o regime democr\u00e1tico. A luta contra o fascismo continua em todo o mundo, com graves amea\u00e7as como, por exemplo, nas \u00faltimas elei\u00e7\u00f5es italianas. O neoliberalismo, totalmente desmascarado com os resultados da pandemia, contribuiu para o ressurgimento do nazifascismo, com as falsas respostas nacionalistas \u00e0 globaliza\u00e7\u00e3o.<br \/>\nReconstruir o Direito Social, especialmente as garantias trabalhistas e previdenci\u00e1rias conquistadas na Constitui\u00e7\u00e3o Cidad\u00e3 de 1988, ser\u00e1 nossa obriga\u00e7\u00e3o. Revogar as \u00faltimas reformas, reconstruindo e modernizando as rela\u00e7\u00f5es de trabalho devidamente formais, e assim recompondo tamb\u00e9m o sistema previdenci\u00e1rio, ter\u00e1 que ser a exig\u00eancia do movimento sindical.<br \/>\nOrganizar e reivindicar ser\u00e1 a tarefa dos sindicatos e centrais sindicais, com objetivo de reconstruir as garantias. O direito trabalhista tem como fun\u00e7\u00e3o principal a defesa da parte mais fraca nas rela\u00e7\u00f5es entre capital e trabalho. O trabalhador tem apenas a sua for\u00e7a de trabalho para vender; assim, a Justi\u00e7a do Trabalho deve recuperar sua raz\u00e3o de exist\u00eancia, em defesa do hipossuficiente. E, da mesma forma, o sistema previdenci\u00e1rio e a assist\u00eancia social tamb\u00e9m precisam readquirir suas obriga\u00e7\u00f5es.<br \/>\nA Previd\u00eancia deve voltar a ser Social, garantindo vida digna aos segurados, abrindo vagas no mercado de trabalho e distribuindo renda por todo o pa\u00eds. A assist\u00eancia aos mais necessitados \u00e9 obriga\u00e7\u00e3o do Estado, dever de qualquer governo. Para recompor a economia, ser\u00e1 preciso garantir a sobreviv\u00eancia dos mais necessitados, sem esmolas. Movimentar a economia a partir dos que t\u00eam que gastar. Esse colunista repetiu muitas vezes: em momentos de crise os que tem dinheiro s\u00f3 guardam, n\u00e3o gastam nada. Quem gasta s\u00e3o os que precisam, comprar comida, pagar aluguel, etc.<br \/>\nVale apontar as principais perversidades presentes atualmente no sistema previdenci\u00e1rio, especialmente com a Emenda Constitucional 103\/2019. Talvez a principal maldade esteja nos c\u00e1lculos dos benef\u00edcios. Todas as aposentadorias, inclusive a por invalidez, s\u00e3o calculadas em 60% da m\u00e9dia para quem tiver at\u00e9 20 anos de contribui\u00e7\u00e3o, acrescentando 2% para cada ano a partir da\u00ed. Importante lembrar que a lei de 1991 dispunha a invalidez em 80% da m\u00e9dia e mais 1% para cada ano, ou seja, com 20 anos de contribui\u00e7\u00e3o teria 100% da m\u00e9dia.<br \/>\nE maldade ainda maior est\u00e1 no c\u00e1lculo da pens\u00e3o por morte, recuando para a regra dos tempos da ditadura, pagando 50% da aposentadoria do falecido, com mais 10% para cada dependente. Assim, a vi\u00fava sozinha ganha 60%. A partir de 1991, passou a ser 80% mais 10% para cada dependente. Apenas em 1995 passou a ser 100% em qualquer hip\u00f3tese.<br \/>\nLembrando a pens\u00e3o da Dona Maria, com o marido, Seu Jo\u00e3o, falecendo antes de se aposentar, com 20 anos de contribui\u00e7\u00f5es. Como ainda n\u00e3o estava aposentado, a base de c\u00e1lculo seria a aposentadoria por invalidez que receberia se ficasse inv\u00e1lido ao inv\u00e9s de morrer, 60% da m\u00e9dia. Portanto, a pens\u00e3o da Dona Maria ser\u00e1 calculada em 60% de 60%, ou seja, apenas 36%, da m\u00e9dia contributiva. Seu Jo\u00e3o tinha trabalhado bastante, algum tempo sem o devido registro, e, com muito esfor\u00e7o, conquistando sua qualifica\u00e7\u00e3o profissional, completou a m\u00e9dia de 5 mil reais mensais. Acontece que, pelas regras atuais, Dona Maria vai ter que ser virar com R$ 1.800.<br \/>\nA esperan\u00e7a voltou, e a luta ser\u00e1 dura, mas compensadora. Reconstruir o Estado Democr\u00e1tico de Direito, com a devida import\u00e2ncia do Direito Social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E, com a esperan\u00e7a, voltam tamb\u00e9m nossas obriga\u00e7\u00f5es na reconstru\u00e7\u00e3o do Estado Democr\u00e1tico de Direito, com a devida import\u00e2ncia ao Direito Social.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-701","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=701"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/701\/revisions"}],"predecessor-version":[{"id":702,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/701\/revisions\/702"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}