{"id":745,"date":"2022-12-08T06:00:28","date_gmt":"2022-12-08T09:00:28","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=745"},"modified":"2022-12-07T17:10:23","modified_gmt":"2022-12-07T20:10:23","slug":"as-vitimas-do-arrastao-pericial","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2022\/12\/08\/as-vitimas-do-arrastao-pericial\/","title":{"rendered":"As v\u00edtimas do \u201carrast\u00e3o pericial\u201d"},"content":{"rendered":"<p>O que a tecnocracia da pior qualidade chamou de \u201cpente fino\u201d, foi, na realidade, um \u201carrast\u00e3o pericial\u201d, agradando os Peritos M\u00e9dicos Federais, com \u201ctarefas extraordin\u00e1ria\u201d valendo pagamento extra mesmo realizadas durante a jornada de trabalho. Come\u00e7ou no governo golpista de 2016, com maiores alcances no desgoverno que logo terminar\u00e1.<br \/>\nA inten\u00e7\u00e3o foi cassar aux\u00edlios-doen\u00e7a e aposentadorias por invalidez atrav\u00e9s de uma an\u00e1lise do perito m\u00e9dico por longos dez minutos. Ora, para aux\u00edlio-doen\u00e7a a per\u00edcia dentro de um certo tempo \u00e9 obriga\u00e7\u00e3o do INSS; \u00e9 preciso definir se o benef\u00edcio ainda segue ou n\u00e3o por um tempo, como tamb\u00e9m a possibilidade de reabilita\u00e7\u00e3o profissional ou a convers\u00e3o em aposentadoria por invalidez. Por\u00e9m, para convocar um aposentado por invalidez para uma per\u00edcia m\u00e9dica \u00e9 preciso ter uma raz\u00e3o; voltou a trabalhar, por exemplo, ou surgiu a cura da doen\u00e7a que tinha ou, quem sabe ainda, descobriram que a concess\u00e3o do benef\u00edcio foi mediante uma fraude na per\u00edcia. Nada disso fundamentou as convoca\u00e7\u00f5es do INSS no \u201carrast\u00e3o\u201d. O resultado foi vergonhoso, com o aumento substancial da mis\u00e9ria e o ac\u00famulo de a\u00e7\u00f5es judiciais da mais caras para o Estado, com per\u00edcias m\u00e9dicas.<br \/>\nO desgoverno derrotado ainda aumentou bastante o universo das \u201cv\u00edtimas\u201d, podendo ser convocado para o \u201carrast\u00e3o pericial\u201d o \u201csegurado em gozo de aux\u00edlio por incapacidade tempor\u00e1ria, aux\u00edlio-acidente ou aposentadoria por invalidez permanente e o pensionista inv\u00e1lido, cujos benef\u00edcios tenham sido concedidos judicial ou administrativamente\u201d.<br \/>\nA perversidade extrapolou, al\u00e9m dos benefici\u00e1rios de aux\u00edlio-doen\u00e7a ou aposentadoria por invalidez, h\u00e1 muito tempo temerosos e expostos \u00e0s tesouras dos peritos m\u00e9dicos, foram inclu\u00eddos os que recebem aux\u00edlio-acidente e os pensionistas inv\u00e1lidos.<br \/>\nO \u201carrast\u00e3o pericial\u201d produziu muitas v\u00edtimas. S\u00e3o trabalhadores afastados da atividade h\u00e1 mais de uma dezena de anos, com mais de 50 anos de idade e sem qualifica\u00e7\u00e3o profissional. Sem nenhuma reabilita\u00e7\u00e3o para o mercado de trabalho e sem milagres que efetivamente recuperem a sua sa\u00fade, receber\u00e1 um agrado disposto na lei, 6 meses com o benef\u00edcio integral, 6 meses com 50% e mais 6 meses com 25%, e muitas vezes, iniciando o benef\u00edcio como desempregado, nem mesmo ter\u00e1 o tempo contado para sua aposentadoria.<br \/>\nSe tiver alguma cobertura, ajuizar\u00e1 a a\u00e7\u00e3o contra o INSS e ainda vai enfrentar a per\u00edcia do juiz, algumas sem a devida aten\u00e7\u00e3o. Recompor as institui\u00e7\u00f5es ser\u00e1 uma dura tarefa do governo eleito, e, al\u00e9m de acabar com os \u201carrast\u00f5es periciais\u201d ainda ter\u00e1 um sem fim de v\u00edtimas, esperando a recomposi\u00e7\u00e3o de seus benef\u00edcios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cassa\u00e7\u00e3o de benef\u00edcios por incapacidade permanente, aposentadorias por invalidez, foi um golpe dos desgovernos contra os que mais necessitam.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-745","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=745"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/745\/revisions"}],"predecessor-version":[{"id":746,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/745\/revisions\/746"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}