{"id":815,"date":"2023-06-05T09:41:30","date_gmt":"2023-06-05T12:41:30","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=815"},"modified":"2023-06-05T09:41:30","modified_gmt":"2023-06-05T12:41:30","slug":"cem-anos-de-previdencia-social","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2023\/06\/05\/cem-anos-de-previdencia-social\/","title":{"rendered":"Cem anos de Previd\u00eancia Social"},"content":{"rendered":"<p>Em janeiro de 1923, foi promulgada a Lei El\u00f3i Chaves, criando as Caixas de Previd\u00eancia para as empresas de estradas de ferro. Importante lembrar que o nosso sindicalismo come\u00e7a com a constru\u00e7\u00e3o das estradas de ferro inglesas, basicamente no estado de S\u00e3o Paulo, com muitos anarco-sindicalistas derrotados na Europa em finais do s\u00e9culo XIX. As Caixas de Previd\u00eancia por empresas foram proliferando descontroladamente e, no Estado Novo de Get\u00falio Vargas surgiram os Institutos de Aposentadoria e Pens\u00f5es, por categorias, como banc\u00e1rios, industri\u00e1rios ou comerci\u00e1rios.<br \/>\nEm 1960, com o movimento sindical bastante fortalecido, foi promulgada a Lei Org\u00e2nica da Previd\u00eancia Social, com a unifica\u00e7\u00e3o do sistema ocorrendo apenas em 1967, j\u00e1 com o golpe militar instalado. Como ainda existia a Guerra Fria, a nossa Previd\u00eancia continuou crescendo, com INPS, INAMPS e IAPAS.<br \/>\nCom a Constitui\u00e7\u00e3o Cidad\u00e3 de 1988, foi constru\u00edda a Seguridade Social brasileira, com a Previd\u00eancia mantendo o car\u00e1ter contributivo, e a Sa\u00fade e Assist\u00eancia Social sob responsabilidade do Estado. Conjug\u00e1vamos o sistema alem\u00e3o, que hav\u00edamos acompanhado em 1923, com o conceito ingl\u00eas ap\u00f3s a Segunda Guerra Mundial. Foi o melhor momento, recompondo a credibilidade do sistema previdenci\u00e1rio e construindo o SUS, Sistema \u00danico de Sa\u00fade.<br \/>\nDepois tivemos trinta anos de pol\u00edticas neoliberais, com a resist\u00eancia do SUS e do INSS comprovada durante a pandemia, por\u00e9m, com muito malef\u00edcios causados; desde as mudan\u00e7as conceituais, com maior import\u00e2ncia ao equil\u00edbrio financeiro e atuarial do que ao cumprimento de suas fun\u00e7\u00f5es sociais, passando por maiores exig\u00eancias e desvirtuamentos dos benef\u00edcios previdenci\u00e1rios, at\u00e9 a maldade maior, estampada na EC 103\/2019, especialmente nos c\u00e1lculos de aposentadorias e pens\u00f5es.<br \/>\nMesmo assim, sobrevivemos e podemos comemorar os cem anos que a Previd\u00eancia Social completa em nossa legisla\u00e7\u00e3o. Com avan\u00e7os e recuos que representam lutas oper\u00e1rias e viol\u00eancias fascistas.<br \/>\nO come\u00e7o do ano com a tentativa de golpe e todas as dificuldades de recompor o Estado Democr\u00e1tico, nem permitiu muitas comemora\u00e7\u00f5es dos cem anos da promulga\u00e7\u00e3o da Lei El\u00f3i Chaves, por\u00e9m, \u00e9 preciso ressaltar a hist\u00f3ria e colocar a recomposi\u00e7\u00e3o de nosso sistema previdenci\u00e1rio na pauta imediata do Governo Lula.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Previd\u00eancia Social brasileira completou cem anos de sua exist\u00eancia na legisla\u00e7\u00e3o.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-815","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=815"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/815\/revisions"}],"predecessor-version":[{"id":816,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/815\/revisions\/816"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}