{"id":832,"date":"2023-07-17T06:00:05","date_gmt":"2023-07-17T09:00:05","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=832"},"modified":"2023-07-15T13:23:03","modified_gmt":"2023-07-15T16:23:03","slug":"a-necessidade-das-contrarreformas-no-direito-social","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2023\/07\/17\/a-necessidade-das-contrarreformas-no-direito-social\/","title":{"rendered":"A necessidade das contrarreformas no Direito Social"},"content":{"rendered":"<p>Com a pandemia e os arroubos fascistas, em todo o mundo civilizado se discute a recomposi\u00e7\u00e3o do Direito Social. Ap\u00f3s tr\u00eas d\u00e9cadas de politicas neoliberais, a mis\u00e9ria se acentuou, com as falsas vitrines desmontadas pelo Covid. O socorro aos necessitados \u00e9 obriga\u00e7\u00e3o dos Estados e garantia para a humanidade. Em nosso pa\u00eds, as perdas dos trabalhadores \u2013 principalmente ap\u00f3s o golpe de 2016 \u2013 e as necessidades imediatas est\u00e3o colocadas. O movimento sindical precisa apresentar suas solu\u00e7\u00f5es e exig\u00eancias.<br \/>\nNem temos o sonho de simplesmente revogar as reformas trabalhista (2017) e previdenci\u00e1ria (2019); n\u00e3o se ressuscita a aposentadoria por tempo de servi\u00e7o ou a m\u00e9dia dos tr\u00eas \u00faltimos anos de contribui\u00e7\u00e3o. Ocorre que existem recomposi\u00e7\u00f5es que devem ser imediatas.<br \/>\nNo campo trabalhista ser\u00e1 preciso recompor a Justi\u00e7a do Trabalho e, especialmente para garantir a Previd\u00eancia Social, regularizar contratos de trabalho formais, com os direitos para os trabalhadores e as devidas contribui\u00e7\u00f5es previdenci\u00e1rias.<br \/>\nNas \u00faltimas semanas comentamos bastante que a recupera\u00e7\u00e3o da credibilidade da nossa Previd\u00eancia Social, al\u00e9m da recomposi\u00e7\u00e3o dos direitos, tamb\u00e9m precisa da retomada da institui\u00e7\u00e3o INSS. Para acabar com a \u201cfila do milh\u00e3o\u201d \u2013 milh\u00e3o de processos administrativos aguardando decis\u00e3o, milh\u00e3o de segurados aguardando per\u00edcia m\u00e9dica \u2013, o Instituto deve ter recompostos seus quadros pessoal e tecnol\u00f3gico, e o Governo Lula come\u00e7ou a tarefa. Cabe aos Sindicatos de Trabalhadores o apoio e a cobran\u00e7a.<br \/>\nE tamb\u00e9m \u00e9 nossa obriga\u00e7\u00e3o, debater cientificamente as necess\u00e1rias altera\u00e7\u00f5es legislativas. A luta contra a mis\u00e9ria e a desigualdade social tamb\u00e9m passa pelo contrato formal de trabalho e pela Previd\u00eancia Social.<br \/>\nOcorre que as grandes perversidades devem ser contidas de imediato. Al\u00e9m de exig\u00eancias absurdas para concess\u00f5es de benef\u00edcios, o que precisa ser mudado com urg\u00eancia \u00e9 a forma de c\u00e1lculos de aposentadorias e pens\u00f5es.<br \/>\nAl\u00e9m da m\u00e9dia pelas contribui\u00e7\u00f5es desde julho de 1994, todas as aposentadorias, inclusive a por invalidez, est\u00e3o sendo calculadas em 60% para quem tiver at\u00e9 20 anos de contribui\u00e7\u00e3o, somando 2% para cada ano a partir da\u00ed, e a pens\u00e3o por morte recuando para os tempos da ditadura, 50% mais 10% para cada dependente. Sempre \u00e9 bom lembrar do trabalhador que tinha quase 20 anos de contribui\u00e7\u00f5es (trabalho sem registro n\u00e3o vale), alcan\u00e7ando uma m\u00e9dia de 5 mil reais; faleceu, deixando apenas a esposa como dependente porque os filhos j\u00e1 est\u00e3o criados; com 60% da aposentadoria que o falecido teria direito, calculada em 60% da m\u00e9dia, sobra para a vi\u00fava a bagatela de 1.800 reais. Temos que recuperar, pelo menos, a forma de c\u00e1lculo disposta na lei em 1991, para a invalidez em 80% da m\u00e9dia, com mais 1% para cada ano de contribui\u00e7\u00e3o, e para a por idade, em 70% da m\u00e9dia, acrescentando 1% para cada ano. E a pens\u00e3o em 80% da aposentadoria do segurado falecido, com mais 10% para cada dependente.<br \/>\nEm todos os benef\u00edcios podemos ter o limite de 100% da m\u00e9dia, mas ser\u00e1 obrigat\u00f3ria a revis\u00e3o dos que foram concedidos no per\u00edodo tenebroso. E os novos c\u00e1lculos exigem urg\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O movimento sindical precisa apresentar suas exig\u00eancias, especialmente na contrarreforma dos direitos trabalhista e previdenci\u00e1rio.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-832","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=832"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/832\/revisions"}],"predecessor-version":[{"id":833,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/832\/revisions\/833"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}