{"id":834,"date":"2023-07-24T06:00:29","date_gmt":"2023-07-24T09:00:29","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=834"},"modified":"2023-07-21T12:28:30","modified_gmt":"2023-07-21T15:28:30","slug":"a-media-como-base-de-calculo","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2023\/07\/24\/a-media-como-base-de-calculo\/","title":{"rendered":"A m\u00e9dia como base de c\u00e1lculo"},"content":{"rendered":"<p>Os c\u00e1lculos das aposentadorias se fazem em duas partes: a base de c\u00e1lculo e o percentual aplicado. A grande diferen\u00e7a que havia entre o benef\u00edcio pago pelo Regime Geral (INSS) e a aposentadoria do servidor p\u00fablico era a base de c\u00e1lculo, entre uma m\u00e9dia de contribui\u00e7\u00f5es e o \u00faltimo sal\u00e1rio recebido. Lembrem-se que n\u00e3o \u00e9 mais assim; todos agora s\u00e3o calculados pela m\u00e9dia contributiva.<br \/>\nTamb\u00e9m \u00e9 importante observar a pol\u00edtica neoliberal imposta com a EC 20\/1998; no lugar da obriga\u00e7\u00e3o social de manter seu segurado em condi\u00e7\u00f5es pr\u00f3ximas a que ele teria se estivesse trabalhando, apontam a obriga\u00e7\u00e3o do \u201cequil\u00edbrio financeiro e atuarial\u201d em uma conta que nunca foi feita.<br \/>\nPara recompor a credibilidade do nosso sistema previdenci\u00e1rio, a Constitui\u00e7\u00e3o Cidad\u00e3, em 1988, determinou o c\u00e1lculo das aposentadorias pela m\u00e9dia das 36 \u00faltimas contribui\u00e7\u00f5es, com a devida atualiza\u00e7\u00e3o monet\u00e1ria. Ap\u00f3s dez anos, o neoliberalismo retirou a garantia constitucional, abrindo espa\u00e7o para a m\u00e9dia dos maiores sal\u00e1rios que representassem 80% de todos. Um c\u00e1lculo infame, para garantir o dinheiro do sistema e n\u00e3o a manuten\u00e7\u00e3o do segurado. Por incr\u00edvel que pare\u00e7a, na atualidade ficou pior; a partir da EC 103\/2019, vale a m\u00e9dia sobre todas as contribui\u00e7\u00f5es desde julho\/1994, sem nem retirar os 20% nas contribui\u00e7\u00f5es menores.<br \/>\nNas contrarreformas que devem ser propostas \u2013 semana passada falamos dos percentuais \u2013 a base de c\u00e1lculo tamb\u00e9m merece debate. A m\u00e9dia de todas as contribui\u00e7\u00f5es, de julho de 1994 at\u00e9 o in\u00edcio da aposentadoria, pode ser muito interessante para planos de previd\u00eancia privada, com a rela\u00e7\u00e3o direta entre todos os valores das contribui\u00e7\u00f5es e o benef\u00edcio; para o Seguro Social n\u00e3o passa de uma maldade.<br \/>\nNem tanto ao mar, nem tanto \u00e0 terra, n\u00e3o podemos nos curvar ao falso c\u00e1lculo atuarial, punitivo ao segurado, mas tamb\u00e9m n\u00e3o teremos a aposentadoria pelo \u00faltimo sal\u00e1rio ou pela m\u00e9dia dos tr\u00eas \u00faltimos anos. Por\u00e9m, \u00e9 poss\u00edvel e obrigat\u00f3rio um c\u00e1lculo mais favor\u00e1vel aos trabalhadores, contabilizando as maiores contribui\u00e7\u00f5es de um per\u00edodo razo\u00e1vel. Como o maior per\u00edodo de car\u00eancia \u00e9 de 15 anos, para aposentadoria por idade, uma boa m\u00e9dia poderia ser pelas maiores 180 contribui\u00e7\u00f5es ap\u00f3s julho de 1994.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como na \u00faltima semana falamos dos percentuais aplicados nos c\u00e1lculos de aposentadorias e pens\u00f5es, vamos conversar um pouco sobre a base de c\u00e1lculo, a m\u00e9dia de contribui\u00e7\u00f5es.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-834","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=834"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/834\/revisions"}],"predecessor-version":[{"id":835,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/834\/revisions\/835"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}