{"id":845,"date":"2023-08-21T06:00:32","date_gmt":"2023-08-21T09:00:32","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=845"},"modified":"2023-08-18T18:14:43","modified_gmt":"2023-08-18T21:14:43","slug":"ainda-a-periculosidade-e-a-aposentadoria-especial","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2023\/08\/21\/ainda-a-periculosidade-e-a-aposentadoria-especial\/","title":{"rendered":"Ainda a periculosidade e a Aposentadoria Especial"},"content":{"rendered":"<p>Um dia desses conversamos sobre tal tema, e destacamos que a EC 103\/2019 praticamente extinguiu a Aposentadoria por Tempo de Servi\u00e7o\/Contribui\u00e7\u00e3o, arrastando junto a Aposentadoria Especial, passando a ser vinculada \u00e0 idade do segurado. Lembrando que isso n\u00e3o modifica seu conceito, criado pela LOPS de 1960, reduzindo a exig\u00eancia laboral para os trabalhadores em atividades insalubres, periculosas ou penosas.<br \/>\nAssim, completando o tempo m\u00ednimo em atividade especial, 25 anos, 20 anos ou 15 anos, dependendo da atividade, o segurado ter\u00e1 a redu\u00e7\u00e3o da idade exigida, seja homem (65) ou mulher (62), para, respectivamente, 60, 58 ou 55 anos. Para quem j\u00e1 estava no sistema, a regra de transi\u00e7\u00e3o exige a somat\u00f3ria de tempo de contribui\u00e7\u00e3o com idade, completando, respectivamente, 86, 76 e 66.<br \/>\nConforme j\u00e1 contei, em 1995, a tecnocracia neoliberal quis mudar a defini\u00e7\u00e3o do benef\u00edcio especial, pretendendo que fosse uma aposentadoria por \u201cinvalidez presumida\u201d. Apenas a insalubridade daria direito \u00e0 Especial, com a periculosidade s\u00f3 valendo se o risco acontecesse, se a invalidez fosse efetiva.<br \/>\nA corre\u00e7\u00e3o dessa p\u00e9ssima interpreta\u00e7\u00e3o do INSS ocorreu judicialmente. A partir do Decreto 2.172\/1997, o INSS deixou de considerar o tempo de exposi\u00e7\u00e3o a explosivos, eletricidade e outros agentes periculosos, como especial.<br \/>\nA consagra\u00e7\u00e3o nos tribunais, inclusive no STJ, reafirma a defini\u00e7\u00e3o do benef\u00edcio especial, conforme a LOPS de 1960. Confirmaram que os decretos regulamentadores n\u00e3o s\u00e3o restritivos; tem o car\u00e1ter meramente exemplificativo. Portanto, todas os agentes que podem causar preju\u00edzo \u00e0 sa\u00fade ou \u00e0 integridade f\u00edsica dos trabalhadores caracterizam o direito ao benef\u00edcio especial.<br \/>\nO decreto regulamentador de 1964 definia a atividade do vigilante armado, mas o STJ afirma que com ou sem o uso de armas, a atividade do vigilante, habitual e permanente, o exp\u00f5e aos riscos.<br \/>\nSem admitir d\u00favidas, a Aposentadoria Especial \u00e9 devida aos trabalhadores que atuam, de forma habitual e permanente, em condi\u00e7\u00f5es insalubres, periculosas ou penosas. E ainda temos que lutar para sua recomposi\u00e7\u00e3o na lei, principalmente nos c\u00e1lculos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No pr\u00f3ximo dia 29 de agosto, a OAB de S\u00e3o Vicente vai realizar o 2\u00ba Semin\u00e1rio de Direito Previdenci\u00e1rio, e fomos convidados a falar sobre A periculosidade como motivadora de Aposentadoria Especial.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-845","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=845"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/845\/revisions"}],"predecessor-version":[{"id":846,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/845\/revisions\/846"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}