{"id":848,"date":"2023-08-28T06:00:52","date_gmt":"2023-08-28T09:00:52","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=848"},"modified":"2023-08-25T16:00:06","modified_gmt":"2023-08-25T19:00:06","slug":"continuam-adiando-a-revisao-da-vida-toda","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2023\/08\/28\/continuam-adiando-a-revisao-da-vida-toda\/","title":{"rendered":"Continuam adiando a revis\u00e3o da vida toda"},"content":{"rendered":"<p>O STF, apesar de consagrar a vit\u00f3ria dos trabalhadores nas revis\u00f5es de aposentadorias pela m\u00e9dia da vida toda, mant\u00e9m suspensos os processos, admitindo as fantasias que a tecnocracia alega.<br \/>\nA mat\u00e9ria nem \u00e9 dif\u00edcil de entender. A Lei 9.876, em 1999, substituiu a base de c\u00e1lculo de ent\u00e3o, m\u00e9dia dos 36 \u00faltimos sal\u00e1rios, pela \u201cm\u00e9dia simples dos maiores sal\u00e1rios-de-contribui\u00e7\u00e3o correspondente a oitenta por cento de todo o per\u00edodo contributivo\u201d. Por\u00e9m, disp\u00f4s como regra de transi\u00e7\u00e3o, para quem j\u00e1 estava no sistema previdenci\u00e1rio, que a m\u00e9dia se faria sobre os maiores sal\u00e1rios representando o \u201cper\u00edodo contributivo desde a compet\u00eancia julho de 1994\u201d.<br \/>\nTodo mundo sabe que regras de transi\u00e7\u00e3o, principalmente nas reformas previdenci\u00e1rias, s\u00e3o sempre mais favor\u00e1veis aos trabalhadores que j\u00e1 estavam vinculados ao sistema. Com as mudan\u00e7as nas regras \u201cno meio do jogo\u201d, a transi\u00e7\u00e3o busca diminuir as perdas para quem j\u00e1 \u201cjogava a partida\u201d. Assim, quando a regra de transi\u00e7\u00e3o for desfavor\u00e1vel, n\u00e3o pode ser aplicada, e assim \u00e9 o entendimento do STF.<br \/>\nConforme repetimos muitas vezes, diferentemente das alega\u00e7\u00f5es tecnocr\u00e1ticas fantasiosas, a revis\u00e3o da m\u00e9dia da vida toda n\u00e3o se aplica para muita gente. \u00c9 preciso que essa m\u00e9dia, computando os maiores sal\u00e1rios que representem 80% de toda a vida laboral, fique superior \u00e0 aplica\u00e7\u00e3o da regra de transi\u00e7\u00e3o, a partir de julho de 1994. Portanto, \u00e9 necess\u00e1rio que os sal\u00e1rios-de-contribui\u00e7\u00e3o do aposentado sejam, no per\u00edodo anterior a 1994, maiores, e quanto mais tempo passa, menores s\u00e3o as chances de tal fato acontecer.<br \/>\nE ainda temos a decad\u00eancia, prazo de dez anos para reclamar a revis\u00e3o, desde a data da concess\u00e3o do benef\u00edcio ou do primeiro pagamento. A EC 103, em 13\/11\/2019, al\u00e9m de ampliar a m\u00e9dia para todas as contribui\u00e7\u00f5es, sem nem mesmo descontar as 20% menores, n\u00e3o disp\u00f4s regra de transi\u00e7\u00e3o: a m\u00e9dia se faz apenas de julho de 1994 pra frente, em todos os casos, para quem j\u00e1 estava no sistema previdenci\u00e1rio ou para quem entrou depois.<br \/>\nAl\u00e9m de serem poucas a\u00e7\u00f5es no presente e no futuro (para benef\u00edcios concedidos entre agosto de 2013 e 12\/11\/2019, e com a m\u00e9dia da vida toda mais favor\u00e1vel), n\u00e3o existiriam as d\u00edvidas se o INSS cumprisse a lei, aplicando a regra de transi\u00e7\u00e3o apenas em favor do segurado.<br \/>\nCom a decis\u00e3o coerente do STF, agora \u00e9 preciso deixar os processos correrem. Os aposentados querem Justi\u00e7a, em tempo de aproveit\u00e1-la.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguem suspensos os processos judiciais que buscam a revis\u00e3o pela m\u00e9dia da vida toda, com alega\u00e7\u00f5es que n\u00e3o representam a realidade.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-848","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=848"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/848\/revisions"}],"predecessor-version":[{"id":849,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/848\/revisions\/849"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}