{"id":952,"date":"2025-06-09T06:00:08","date_gmt":"2025-06-09T09:00:08","guid":{"rendered":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/?p=952"},"modified":"2025-06-05T15:49:38","modified_gmt":"2025-06-05T18:49:38","slug":"a-crise-do-inss","status":"publish","type":"post","link":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/2025\/06\/09\/a-crise-do-inss\/","title":{"rendered":"A crise do INSS"},"content":{"rendered":"<p>Basta aparecerem problemas, como os descontos indevidos nos proventos de aposentados e as filas de segurados aguardando benef\u00edcios, para a tecnocracia querer descontar outra vez nos mais pobres: novamente est\u00e3o propondo a desvincula\u00e7\u00e3o entre o m\u00ednimo previdenci\u00e1rio e o sal\u00e1rio m\u00ednimo. Como se fosse poss\u00edvel o trabalhador inativo e seus dependentes sobreviverem com valores abaixo do piso constitucional.<\/p>\n<p>Quanto aos descontos indevidos e empr\u00e9stimos indesejados, o combate deve ser constante, sempre, vigilante. Por\u00e9m, a crise mesmo se apresenta em raz\u00e3o de dois desmontes. Por um lado, dos contratos formais de trabalho, com \u201cempreendimentos\u201d e \u201cuberiza\u00e7\u00f5es\u201d; por outro, o disjunte da pr\u00f3pria institui\u00e7\u00e3o, obedecendo \u00e0 desgastada ideia de \u201cEstado M\u00ednimo\u201d.<\/p>\n<p>A procuradoria do INSS foi engolida pela AGU (Advocacia Geral da Uni\u00e3o) e os fiscais da Previd\u00eancia agora pertencem \u00e0 Receita Federal. Sem a dedica\u00e7\u00e3o especializada, certamente n\u00e3o v\u00e3o incomodar empresas empregadoras sobre as condi\u00e7\u00f5es de trabalho dos empregados segurados, as aposentadorias especiais e os acidentes do trabalho. Atualmente, nem os m\u00e9dicos peritos pertencem aos quadros do INSS. Em 2019, a tenebrosa Emenda Constitucional 103 completou o cerco sobre o servi\u00e7o p\u00fablico. Os funcion\u00e1rios da autarquia que j\u00e1 haviam adquirido o direito \u00e0 aposentadoria, n\u00e3o tiveram d\u00favidas, causando o esvaziamento do INSS, especialmente de seus melhores funcion\u00e1rios, que mais entendiam de legisla\u00e7\u00e3o e de segurados. A contrata\u00e7\u00e3o de militares da reserva, que nada entendiam do assunto, s\u00f3 aumentou as filas.<\/p>\n<p>Para as per\u00edcias m\u00e9dicas, ainda inventaram o \u201cpente fino\u201d, buscando cancelar benef\u00edcios por incapacidades, at\u00e9 mesmo as permanentes aposentadorias por invalidez. Com a cria\u00e7\u00e3o do chamado Atesmed, (concess\u00e3o de benef\u00edcios por per\u00edodos menores sem a obrigat\u00f3ria per\u00edcia presencial) somente os peritos m\u00e9dicos reclamaram. Reclamaram tanto que passaram a interferir nas concess\u00f5es de tais benef\u00edcios, contrapondo-se aos laudos m\u00e9dicos e exames anexados, sem a m\u00ednima considera\u00e7\u00e3o pelo trabalho de colegas.<\/p>\n<p>Recuperar o Instituto Nacional do Seguro Social, inclusive com os devidos concursos, \u00e9 uma obriga\u00e7\u00e3o de qualquer governo democr\u00e1tico. J\u00e1, urgente, para garantir sua sobreviv\u00eancia financeira, precisamos \u00e9 do crescimento econ\u00f4mico, com empregos e consumo, inclusive regulamentando novos tipos de contratos formais de trabalho, com direitos e garantias, inclusive a participa\u00e7\u00e3o no Seguro Social.<\/p>\n<p>A Constitui\u00e7\u00e3o Cidad\u00e3, em cl\u00e1usulas p\u00e9treas, determina que \u201cnenhum benef\u00edcio que substitua o sal\u00e1rio de contribui\u00e7\u00e3o ou o rendimento do trabalho do segurado (como as aposentadorias e pens\u00f5es por morte) ter\u00e1 valor mensal inferior ao sal\u00e1rio m\u00ednimo\u201d que, por sua vez, deve ser \u201ccapaz de atender a suas necessidades vitais b\u00e1sicas e \u00e0s de sua fam\u00edlia com moradia, alimenta\u00e7\u00e3o, educa\u00e7\u00e3o, sa\u00fade, lazer, vestu\u00e1rio, higiene, transporte e previd\u00eancia social\u201d. Certamente, a proposta tecnocr\u00e1tica de matar aposentados e pensionistas de fome, deve ser veementemente repudiada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado na Tribuna Livre em 09\/06\/2025.<\/p>\n<p>Crise do INSS, garantias constitucionais, sal\u00e1rio m\u00ednimo.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-952","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/comments?post=952"}],"version-history":[{"count":1,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/952\/revisions"}],"predecessor-version":[{"id":953,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/posts\/952\/revisions\/953"}],"wp:attachment":[{"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/media?parent=952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/categories?post=952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pardaladvocacia.com.br\/direitoprevidenciario\/wp-json\/wp\/v2\/tags?post=952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}